{"id":5,"date":"2015-04-14T17:26:12","date_gmt":"2015-04-14T17:26:12","guid":{"rendered":"http:\/\/impreza2.us-themes.com\/?page_id=5"},"modified":"2021-04-28T17:31:53","modified_gmt":"2021-04-28T15:31:53","slug":"home","status":"publish","type":"page","link":"https:\/\/rugexport.de\/es\/","title":{"rendered":"Home"},"content":{"rendered":"<section class=\"l-section wpb_row height_medium full_height valign_center color_secondary with_img\" id=\"home\"><div class=\"l-section-img\" data-img-width=\"1920\" data-img-height=\"1080\" style=\"background-image: url(https:\/\/rugexport.de\/wp-content\/uploads\/2020\/10\/fondo-header-1.jpg);background-repeat: no-repeat;\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container align_center\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_center\"><div class=\"w-image-h\"><img width=\"400\" height=\"272\" src=\"https:\/\/rugexport.de\/wp-content\/uploads\/2020\/10\/Logo_RUG_web.png\" class=\"attachment-us_400_0 size-us_400_0\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/rugexport.de\/wp-content\/uploads\/2020\/10\/Logo_RUG_web.png 683w, https:\/\/rugexport.de\/wp-content\/uploads\/2020\/10\/Logo_RUG_web-620x422.png 620w, https:\/\/rugexport.de\/wp-content\/uploads\/2020\/10\/Logo_RUG_web-500x340.png 500w, https:\/\/rugexport.de\/wp-content\/uploads\/2020\/10\/Logo_RUG_web-350x238.png 350w, https:\/\/rugexport.de\/wp-content\/uploads\/2020\/10\/Logo_RUG_web-400x272.png 400w, https:\/\/rugexport.de\/wp-content\/uploads\/2020\/10\/Logo_RUG_web-300x204.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div><\/div>[vc_custom_heading text=\u00bbVenta Estrat\u00e9gica Internacional\u00bb font_container=\u00bbtag:h3|text_align:center\u00bb use_theme_fonts=\u00bbyes\u00bb css=\u00bb%7B%22default%22%3A%7B%22color%22%3A%22%235f4b8b%22%2C%22font-size%22%3A%222.6rem%22%7D%7D\u00bb]<div class=\"w-separator size_small\"><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_3\" href=\"#about\"><span class=\"w-btn-label\">La Empresa<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/section><!-- Row Backgrounds --><div class=\"upb_bg_img\" data-ultimate-bg=\"url(https:\/\/rugexport.de\/wp-content\/uploads\/2018\/09\/rawpixel-593597-unsplash.jpg)\" data-image-id=\"id^1101|url^http:\/\/rugexport.de\/wp-content\/uploads\/2018\/09\/rawpixel-593597-unsplash.jpg|caption^null|alt^null|title^rawpixel-593597-unsplash|description^null\" data-ultimate-bg-style=\"vcpb-default\" data-bg-img-repeat=\"no-repeat\" data-bg-img-size=\"cover\" data-bg-img-position=\"\" data-parallx_sense=\"30\" data-bg-override=\"ex-full\" data-bg_img_attach=\"scroll\" data-upb-overlay-color=\"\" data-upb-bg-animation=\"\" data-fadeout=\"\" data-bg-animation=\"left-animation\" data-bg-animation-type=\"h\" data-animation-repeat=\"repeat\" data-fadeout-percentage=\"30\" data-parallax-content=\"\" data-parallax-content-sense=\"30\" data-row-effect-mobile-disable=\"true\" data-img-parallax-mobile-disable=\"true\" data-rtl=\"false\"  data-custom-vc-row=\"\"  data-vc=\"6.8.0\"  data-is_old_vc=\"\"  data-theme-support=\"\"   data-overlay=\"false\" data-overlay-color=\"\" data-overlay-pattern=\"\" data-overlay-pattern-opacity=\"\" data-overlay-pattern-size=\"\"    data-seperator=\"true\"  data-seperator-type=\"xlarge_triangle_seperator\"  data-seperator-shape-size=\"40\"  data-seperator-svg-height=\"140\"  data-seperator-full-width=\"true\" data-seperator-position=\"bottom_seperator\"  data-seperator-background-color=\"#ffffff\"  data-icon=\"\"  ><\/div><section class=\"l-section wpb_row height_medium color_alternate\" id=\"services\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2><strong>Nuestros Servicios<\/strong><\/h2>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_boxes stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox iconpos_top style_default color_primary align_center no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:48px;\"><i class=\"fas fa-cube\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\">Penetraci\u00f3n y desarrollo comercial en entidades p\u00fablicas.<\/h4><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox iconpos_top style_default color_primary align_center no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:48px;\"><i class=\"far fa-hand-point-up\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\">Preparaci\u00f3n y gesti\u00f3n de licitaciones p\u00fablicas.<\/h4><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox iconpos_top style_default color_primary align_center no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:48px;\"><i class=\"fas fa-chart-area\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\">Desarrollo de producto y estrategia de comunicaci\u00f3n comercial.<\/h4><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox iconpos_top style_default color_primary align_center no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:48px;\"><i class=\"material-icons\">euro_symbol<\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\">Introducci\u00f3n comercial en grandes corporaciones, industria y retail.<\/h4><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_3f8cae2b has_text_color height_huge\" id=\"about\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container align_center us_animate_afb\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: center;\"><b>Hacemos posible la expansi\u00f3n Internacional\u00a0<\/b><\/h2>\n<p style=\"text-align: justify;\">Nos hemos especializado en el desarrollo comercial internacional de peque\u00f1as y medianas empresas tecnol\u00f3gicas. El objeto principal de nuestra actividad es la venta directa a clientes complejos: corporaciones y entidades p\u00fablicas. Nos preocupamos de estudiar y desarrollar la f\u00f3rmula de venta o distribuci\u00f3n m\u00e1s eficiente \u00a0para cada producto o tecnologia.<\/p>\n<p style=\"text-align: justify;\">El alcance geogr\u00e1fico de nuestra actividad se sit\u00faa en Alemania, Francia, \u00a0Espa\u00f1a, B\u00e9lgica, Suiza y Austria.<\/p>\n<p style=\"text-align: justify;\">Mercados: \u00a0Seguridad y Protecci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Desarrollamos una venta creativa que incentiva la realizaci\u00f3n de procesos y \u00a0desarrollos tecnol\u00f3gicos que permite la adecuaci\u00f3n final de la tecnolog\u00eda al mercado objetivo. Entendemos esta acomodaci\u00f3n como un factor clave para el \u00e9xito de la oferta y el desarrollo comercial de nuestros clientes.<\/p>\n<p style=\"text-align: justify;\">Funcionamos como un departamento de exportaci\u00f3n externo para empresas \u00a0que no cuentan con una infraestructura comercial internacional, tanto en Business-to-Business como en Business to Administration, es decir con la preparaci\u00f3n y ejecuci\u00f3n de licitaciones privadas y p\u00fablicas.<\/p>\n<\/div><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_4 us_custom_1e0e9307 icon_atleft\" href=\"#team\"><i class=\"far fa-futbol\"><\/i><span class=\"w-btn-label\">Equipo Humano<\/span><\/a><\/div><div class=\"w-separator size_medium\"><\/div><\/div><\/div><\/div><\/div><\/div><\/section><!-- Row Backgrounds --><div class=\"upb_color\" data-bg-override=\"0\" data-bg-color=\"\" data-fadeout=\"\" data-fadeout-percentage=\"30\" data-parallax-content=\"\" data-parallax-content-sense=\"30\" data-row-effect-mobile-disable=\"true\" data-img-parallax-mobile-disable=\"true\" data-rtl=\"false\"  data-custom-vc-row=\"\"  data-vc=\"6.8.0\"  data-is_old_vc=\"\"  data-theme-support=\"\"   data-overlay=\"false\" data-overlay-color=\"\" data-overlay-pattern=\"\" data-overlay-pattern-opacity=\"\" data-overlay-pattern-size=\"\"    data-seperator=\"true\"  data-seperator-type=\"xlarge_triangle_seperator\"  data-seperator-shape-size=\"40\"  data-seperator-svg-height=\"100\"  data-seperator-full-width=\"true\" data-seperator-position=\"bottom_seperator\"  data-seperator-background-color=\"#ffffff\"  data-icon=\"\"  ><\/div><section class=\"l-section wpb_row height_medium\" id=\"advantages\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2><strong>\u00bfPor qu\u00e9 elegir nuestra\u00a0empresa?<\/strong><\/h2>\n<\/div><\/div><div class=\"w-separator size_medium with_line width_30 thick_1 style_solid color_border align_center with_content\"><div class=\"w-separator-h\"><i class=\"fas fa-chevron-down\"><\/i><\/div><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-4 wpb_column vc_column_container us_animate_afb\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox iconpos_left style_outlined color_primary align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><i class=\"fas fa-rocket\"><\/i><\/div><div class=\"w-iconbox-meta\"><h3 class=\"w-iconbox-title\"><strong>Desde tu Empresa al Mundo<\/strong><\/h3><div class=\"w-iconbox-text\"><p>Facilitamos la expansi\u00f3n Internacional de peque\u00f1as y medianas empresas que proponen productos diferenciados en mercados de dif\u00edcil penetraci\u00f3n y venta compleja.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container us_animate_afb\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox iconpos_left style_outlined color_primary align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><i class=\"fas fa-bolt\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\"><strong>Experiencia en Venta Internacional<\/strong><\/h4><div class=\"w-iconbox-text\"><p>Ofrecemos a nuestros clientes experiencia en contextos de venta diversos e internacionales.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container us_animate_afb\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox iconpos_left style_outlined color_primary align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:28px;\"><i class=\"far fa-heart\"><\/i><\/div><div class=\"w-iconbox-meta\"><h3 class=\"w-iconbox-title\"><strong>Multiculturalidad<\/strong><\/h3><div class=\"w-iconbox-text\"><p>Creemos en un mercado global que respete las diferencias. La sensibilidad multicultural es uno de nuestros valores fundamentales ante el desarrollo relaciones comerciales en un entorno internacional.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium full_height valign_center color_alternate\" id=\"team\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container us_animate_afb\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: center;\"><b>Equipo Humano<\/b><\/h2>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">El \u00e9xito de nuestra actividad se fundamenta en una amplia experiencia comercial, presencia internacional y en la continua interacci\u00f3n con nuestros partner-clientes.<\/span><\/p>\n<\/div><\/div><div class=\"w-separator size_large\"><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-4 wpb_column vc_column_container us_animate_afb\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-person layout_circle\" itemscope itemtype=\"https:\/\/schema.org\/Person\"><div class=\"w-person-image\"><img width=\"920\" height=\"920\" src=\"https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-2-920x920.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-2-920x920.jpg 920w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-2-53x53.jpg 53w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-2-620x620.jpg 620w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-2-350x350.jpg 350w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-2-500x500.jpg 500w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-2-768x768.jpg 768w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-2-300x300.jpg 300w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-2-600x600.jpg 600w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-2-150x150.jpg 150w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-2-400x400.jpg 400w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-2.jpg 1000w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/div><div class=\"w-person-content\"><h4 itemprop=\"name\" class=\"w-person-name\"><span>Alejandro Rodr\u00edguez<\/span><\/h4><div class=\"w-person-role\" itemprop=\"jobTitle\">M\u00e1rketing y Comunicaci\u00f3n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container us_animate_afb\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-person layout_circle\" itemscope itemtype=\"https:\/\/schema.org\/Person\"><div class=\"w-person-image\"><img width=\"920\" height=\"920\" src=\"https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-4-920x920.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-4-920x920.jpg 920w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-4-53x53.jpg 53w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-4-620x620.jpg 620w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-4-350x350.jpg 350w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-4-500x500.jpg 500w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-4-768x768.jpg 768w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-4-300x300.jpg 300w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-4-600x600.jpg 600w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-4-150x150.jpg 150w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-4-400x400.jpg 400w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-4.jpg 1000w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/div><div class=\"w-person-content\"><h4 itemprop=\"name\" class=\"w-person-name\"><span>Alberto Ruiz Blanco<\/span><\/h4><div class=\"w-person-role\" itemprop=\"jobTitle\">Licitaci\u00f3n P\u00fablica y Privada<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container us_animate_afb\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-person layout_circle\" itemscope itemtype=\"https:\/\/schema.org\/Person\"><div class=\"w-person-image\"><img width=\"920\" height=\"920\" src=\"https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-3-920x920.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-3-920x920.jpg 920w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-3-53x53.jpg 53w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-3-620x620.jpg 620w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-3-350x350.jpg 350w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-3-500x500.jpg 500w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-3-768x768.jpg 768w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-3-300x300.jpg 300w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-3-600x600.jpg 600w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-3-150x150.jpg 150w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-3-400x400.jpg 400w, https:\/\/rugexport.de\/wp-content\/uploads\/2019\/04\/FOTO-CORPORATIVA-3.jpg 1000w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/div><div class=\"w-person-content\"><h4 itemprop=\"name\" class=\"w-person-name\"><span>Javier G\u00f3mez<\/span><\/h4><div class=\"w-person-role\" itemprop=\"jobTitle\">Desarrollo Comercial Retail<br \/>\nProductos de Consumo<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto width_full color_primary\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_boxes stacking_default\"><div class=\"vc_col-sm-6 vc_col-md-3 wpb_column vc_column_container has_bg_color\"><div class=\"vc_column-inner us_custom_c4ae8a24\"><div class=\"wpb_wrapper\"><div class=\"w-counter us_custom_15f8eac5 color_heading align_center has_font_size\" data-duration=\"2\"><div class=\"w-counter-value\"><span class=\"w-counter-value-part type_text\" data-final=\"+\">+<\/span><span class=\"w-counter-value-part type_number\" data-final=\"4\">0<\/span><span class=\"w-counter-value-part type_text\" data-final=\"\"><\/span><\/div><h6 class=\"w-counter-title\">A\u00f1os de experiencia en mercados europeos<\/h6><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 vc_col-md-3 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_6f4bb857\"><div class=\"wpb_wrapper\"><div class=\"w-counter us_custom_15f8eac5 color_heading align_center has_font_size\" data-duration=\"2\"><div class=\"w-counter-value\"><span class=\"w-counter-value-part type_text\" data-final=\"\"><\/span><span class=\"w-counter-value-part type_number\" data-final=\"5\">0<\/span><span class=\"w-counter-value-part type_text\" data-final=\"\"><\/span><\/div><h6 class=\"w-counter-title\">Pa\u00edses europeos como \u00e1rea de especializaci\u00f3n<\/h6><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container has_bg_color\"><div class=\"vc_column-inner us_custom_8b66cb09\"><div class=\"wpb_wrapper\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-3 vc_col-xs-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox iconpos_top style_default color_custom align_center no_title no_text\"><a target=\"_blank\" href=\"#\" rel=\"noopener\" class=\"w-iconbox-link\" aria-label=\"fab|facebook-f\"><div class=\"w-iconbox-icon\" style=\"font-size:48px;--icon-color:#e2e2e2;\"><i class=\"fab fa-facebook-f\"><\/i><\/div><\/a><div class=\"w-iconbox-meta\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 vc_col-xs-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox iconpos_top style_default color_custom align_center no_title no_text\"><a target=\"_blank\" href=\"#\" rel=\"noopener\" class=\"w-iconbox-link\" aria-label=\"fab|linkedin-in\"><div class=\"w-iconbox-icon\" style=\"font-size:48px;--icon-color:#e2e2e2;\"><i class=\"fab fa-linkedin-in\"><\/i><\/div><\/a><div class=\"w-iconbox-meta\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox iconpos_top style_default color_custom align_center no_title no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:48px;--icon-color:#e2e2e2;\"><i class=\"fab fa-xing\"><\/i><\/div><div class=\"w-iconbox-meta\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox iconpos_top style_default color_custom align_center no_title no_text\"><a href=\"mailto:info@rugexport.de\" class=\"w-iconbox-link\" aria-label=\"fas|envelope-open\"><div class=\"w-iconbox-icon\" style=\"font-size:48px;--icon-color:#e2e2e2;\"><i class=\"fas fa-envelope-open\"><\/i><\/div><\/a><div class=\"w-iconbox-meta\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_c6e45089 has_text_color height_medium full_height valign_center\" id=\"contact\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container us_animate_afb\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: center;\"><strong>CONTACTO<\/strong><\/h2>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\" style=\"--additional-gap:10px;\"><div class=\"vc_col-sm-6 wpb_column vc_column_container us_animate_afb\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>No hay nada m\u00e1s importante para nosotros que nuestros clientes. Por favor contacta con nosotros, estamos a tu disposici\u00f3n!<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"w-iconbox iconpos_left style_outlined color_primary align_left no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:20px;\"><i class=\"fas fa-map-marker-alt\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\">Eupenerstr. 124 50933 K\u00f6ln<\/h4><\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"w-iconbox iconpos_left style_outlined color_primary align_left no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:20px;\"><i class=\"fas fa-phone\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\">Tel.+ 49 176 9966 2682 \/ Tel.+ 49 152 3409 9096<\/h4><\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"w-iconbox iconpos_left style_outlined color_primary align_left no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:20px;\"><i class=\"fas fa-envelope\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\">info@rugexport.de<\/h4><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container us_animate_afb\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-2052\"><form id=\"wpforms-form-2052\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"2052\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/pages\/5\" data-token=\"425e85fb56b9557c5a1d4f6094e3e796\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-2052-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-2052-field_1\">Dein Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2052-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Nombre*\" required><\/div><div id=\"wpforms-2052-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-2052-field_2\">Deine E-Mail <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-2052-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"E-Mail*\" required><\/div><div id=\"wpforms-2052-field_4-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"4\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-2052-field_4\">Message <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-2052-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" placeholder=\"Mensaje*\" required><\/textarea><\/div><div id=\"wpforms-2052-field_5-container\" class=\"wpforms-field wpforms-field-captcha\" data-field-id=\"5\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-2052-field_5\">Individuelles Captcha <span class=\"wpforms-required-label\">*<\/span><\/label>\t\t\t<div class=\"wpforms-captcha-math\">\n\t\t\t\t<span class=\"wpforms-captcha-equation\">\n\t\t\t\t\t<span class=\"n1\">15<\/span>\n\t\t\t\t\t\t\t<span class=\"cal\">+<\/span>\n\t\t\t\t\t\t\t<span class=\"n2\">5<\/span>\t\t\t\t\t<span class=\"e\">=<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<input type=\"text\" id=\"wpforms-2052-field_5\" class=\"wpforms-field-medium wpforms-field-required a\" data-rule-wpf-captcha=\"math\" name=\"wpforms[fields][5][a]\" required>\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][5][cal]\" class=\"cal\">\n\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][5][n2]\" class=\"n2\">\n\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][5][n1]\" class=\"n1\">\n\t\t\t<\/div>\n\t\t\t<\/div><\/div><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-2052-field-hp\" class=\"wpforms-field-label\">Message<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-2052-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"2052\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-2052\" class=\"wpforms-submit cfg_boton\" data-alt-text=\"Enviar\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img src=\"https:\/\/rugexport.de\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"[vc_custom_heading text=\"Venta Estrat\u00e9gica Internacional\" font_container=\"tag:h3|text_align:center\" use_theme_fonts=\"yes\" css=\"%7B%22default%22%3A%7B%22color%22%3A%22%235f4b8b%22%2C%22font-size%22%3A%222.6rem%22%7D%7D\"]La EmpresaNuestros Servicios Penetraci\u00f3n y desarrollo comercial en entidades p\u00fablicas.Preparaci\u00f3n y gesti\u00f3n de licitaciones p\u00fablicas.Desarrollo de producto y estrategia de comunicaci\u00f3n comercial.euro_symbolIntroducci\u00f3n comercial en grandes corporaciones, industria y retail.Hacemos posible la expansi\u00f3n Internacional\u00a0 Nos hemos especializado en el desarrollo comercial internacional de peque\u00f1as y medianas empresas tecnol\u00f3gicas. El objeto...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/rugexport.de\/es\/wp-json\/wp\/v2\/pages\/5"}],"collection":[{"href":"https:\/\/rugexport.de\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rugexport.de\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rugexport.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rugexport.de\/es\/wp-json\/wp\/v2\/comments?post=5"}],"version-history":[{"count":120,"href":"https:\/\/rugexport.de\/es\/wp-json\/wp\/v2\/pages\/5\/revisions"}],"predecessor-version":[{"id":2055,"href":"https:\/\/rugexport.de\/es\/wp-json\/wp\/v2\/pages\/5\/revisions\/2055"}],"wp:attachment":[{"href":"https:\/\/rugexport.de\/es\/wp-json\/wp\/v2\/media?parent=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}